{"id":33352,"date":"2019-04-16T10:56:53","date_gmt":"2019-04-16T13:56:53","guid":{"rendered":"https:\/\/www.siqueiracastro.com.br\/noticias\/?p=33352"},"modified":"2019-04-16T10:56:53","modified_gmt":"2019-04-16T13:56:53","slug":"bolsonaro-enaltece-fim-de-conselhos-com-atuacao-da-sociedade","status":"publish","type":"post","link":"https:\/\/www.siqueiracastro.com.br\/noticias\/bolsonaro-enaltece-fim-de-conselhos-com-atuacao-da-sociedade\/","title":{"rendered":"Bolsonaro enaltece fim de conselhos com atua\u00e7\u00e3o da sociedade"},"content":{"rendered":"<p>Folha de S.Paulo repercute o ato assinado pelo presidente Jair Bolsonaro na \u00faltima quinta-feira (11), que pode extinguir dezenas de colegiados da administra\u00e7\u00e3o federal com a participa\u00e7\u00e3o da sociedade civil. Para Rodrigo Oliveira Correia de Brito, especialista em direito administrativo e s\u00f3cio do escrit\u00f3rio da SiqueiraCastro, iniciativas em busca de um aproveitamento consciente dos recursos p\u00fablicos devem ser vistas com bons olhos.<\/p>\n<p><a href=\"https:\/\/www.siqueiracastro.com.br\/noticias\/Noticias\/SCAMidia\/abril-2019\/folha-de-s-paulo-bolsonaro-enaltece-fim-de-conselhos-com-atuacao-da-sociedade.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Leia<\/a> mais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Folha de S.Paulo repercute o ato assinado pelo presidente Jair Bolsonaro na \u00faltima quinta-feira (11), que pode extinguir dezenas de colegiados da administra\u00e7\u00e3o federal com a participa\u00e7\u00e3o da sociedade civil. Para Rodrigo Oliveira Correia de Brito, especialista em direito administrativo e s\u00f3cio do escrit\u00f3rio da SiqueiraCastro, iniciativas em busca de um aproveitamento consciente dos recursos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-33352","post","type-post","status-publish","format-standard","hentry","category-midia"],"fields":{"tdc_dirty_content":["1"],"tdc_icon_fonts":["a:0:{}"],"tdc_google_fonts":["a:0:{}"],"_wpml_word_count":["{\"total\":102,\"to_translate\":{\"en\":102,\"fr\":102,\"es\":102}}"],"_vc_post_settings":["a:1:{s:10:\"vc_grid_id\";a:0:{}}"],"_edit_last":["1"],"_wpml_media_featured":["1"],"_wpml_media_duplicate":["1"],"_alp_processed":["1555423122"],"_wpml_location_migration_done":["1"],"mg_thumb_center":["c"],"mg_search_helper":[""],"mg_hide_feat_img":[""],"mg_link_only":[""],"mg_kenburns_fx":[""],"mg_cust_icon":[""],"mg_layout":["as_default"],"mg_lb_max_w":[""],"mg_lb_feat_match_txt":[""],"mg_lb_img_display_mode":["feat_w"],"mg_img_maxheight":[""],"mg_lb_img_fx":[""],"slide_template":["default"],"video_format_choose":["youtube"],"gallery_type":["slider"],"_wpb_vc_js_status":["false"],"qode_page_background_image_fixed":["yes"],"qode_hide-featured-image":["yes"],"qode_post_style_masonry_date_image":["full"],"qode_post_style_masonry_gallery":["default"],"qode_header-style":["dark"],"qode_show-sidebar":["default"],"qode_seo_title":["Bolsonaro enaltece fim de conselhos com atua\u00e7\u00e3o da sociedade"],"qode_seo_keywords":["Bolsonaro enaltece fim de conselhos com atua\u00e7\u00e3o da sociedade"],"qode_seo_description":["Bolsonaro enaltece fim de conselhos com atua\u00e7\u00e3o da sociedade"],"veiculo":["Folha de S.Paulo"],"_veiculo":["field_5c700349da302"],"fonte":["Rodrigo Oliveira Correia de Brito"],"_fonte":["field_5c700352da303"],"post_views_count":["1391"],"entity_url":["\/post\/bolsonaro_enaltece_fim_de_conselhos_com_atuacao_da_sociedade"]},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bolsonaro enaltece fim de conselhos com atua\u00e7\u00e3o da sociedade - Not\u00edcias | Siqueira Castro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.siqueiracastro.com.br\/noticias\/bolsonaro-enaltece-fim-de-conselhos-com-atuacao-da-sociedade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bolsonaro enaltece fim de conselhos com atua\u00e7\u00e3o da sociedade - Not\u00edcias | Siqueira Castro\" \/>\n<meta property=\"og:description\" content=\"Folha de S.Paulo repercute o ato assinado pelo presidente Jair Bolsonaro na \u00faltima quinta-feira (11), que pode extinguir dezenas de colegiados da administra\u00e7\u00e3o federal com a participa\u00e7\u00e3o da sociedade civil. Para Rodrigo Oliveira Correia de Brito, especialista em direito administrativo e s\u00f3cio do escrit\u00f3rio da SiqueiraCastro, iniciativas em busca de um aproveitamento consciente dos recursos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.siqueiracastro.com.br\/noticias\/bolsonaro-enaltece-fim-de-conselhos-com-atuacao-da-sociedade\/\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias | Siqueira Castro\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/siqueiracastro.advogados\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-16T13:56:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@_SiqueiraCastro\" \/>\n<meta name=\"twitter:site\" content=\"@_SiqueiraCastro\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/bolsonaro-enaltece-fim-de-conselhos-com-atuacao-da-sociedade\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/bolsonaro-enaltece-fim-de-conselhos-com-atuacao-da-sociedade\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Bolsonaro enaltece fim de conselhos com atua\u00e7\u00e3o da sociedade\",\"datePublished\":\"2019-04-16T13:56:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/bolsonaro-enaltece-fim-de-conselhos-com-atuacao-da-sociedade\\\/\"},\"wordCount\":79,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/#organization\"},\"articleSection\":[\"M\u00eddia\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/bolsonaro-enaltece-fim-de-conselhos-com-atuacao-da-sociedade\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/bolsonaro-enaltece-fim-de-conselhos-com-atuacao-da-sociedade\\\/\",\"url\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/bolsonaro-enaltece-fim-de-conselhos-com-atuacao-da-sociedade\\\/\",\"name\":\"Bolsonaro enaltece fim de conselhos com atua\u00e7\u00e3o da sociedade - Not\u00edcias | Siqueira Castro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/#website\"},\"datePublished\":\"2019-04-16T13:56:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/bolsonaro-enaltece-fim-de-conselhos-com-atuacao-da-sociedade\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/bolsonaro-enaltece-fim-de-conselhos-com-atuacao-da-sociedade\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/bolsonaro-enaltece-fim-de-conselhos-com-atuacao-da-sociedade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bolsonaro enaltece fim de conselhos com atua\u00e7\u00e3o da sociedade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/\",\"name\":\"Not\u00edcias | Siqueira Castro\",\"description\":\"Not\u00edcias Siqueira Castro\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/#organization\",\"name\":\"Not\u00edcias | Siqueira Castro\",\"url\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/wp-content\\\/uploads\\\/04\\\/logo-sca-mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/wp-content\\\/uploads\\\/04\\\/logo-sca-mobile.png\",\"width\":286,\"height\":70,\"caption\":\"Not\u00edcias | Siqueira Castro\"},\"image\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/siqueiracastro.advogados\",\"https:\\\/\\\/x.com\\\/_SiqueiraCastro\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bolsonaro enaltece fim de conselhos com atua\u00e7\u00e3o da sociedade - Not\u00edcias | Siqueira Castro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.siqueiracastro.com.br\/noticias\/bolsonaro-enaltece-fim-de-conselhos-com-atuacao-da-sociedade\/","og_locale":"pt_BR","og_type":"article","og_title":"Bolsonaro enaltece fim de conselhos com atua\u00e7\u00e3o da sociedade - Not\u00edcias | Siqueira Castro","og_description":"Folha de S.Paulo repercute o ato assinado pelo presidente Jair Bolsonaro na \u00faltima quinta-feira (11), que pode extinguir dezenas de colegiados da administra\u00e7\u00e3o federal com a participa\u00e7\u00e3o da sociedade civil. Para Rodrigo Oliveira Correia de Brito, especialista em direito administrativo e s\u00f3cio do escrit\u00f3rio da SiqueiraCastro, iniciativas em busca de um aproveitamento consciente dos recursos [&hellip;]","og_url":"https:\/\/www.siqueiracastro.com.br\/noticias\/bolsonaro-enaltece-fim-de-conselhos-com-atuacao-da-sociedade\/","og_site_name":"Not\u00edcias | Siqueira Castro","article_publisher":"https:\/\/www.facebook.com\/siqueiracastro.advogados","article_published_time":"2019-04-16T13:56:53+00:00","twitter_card":"summary_large_image","twitter_creator":"@_SiqueiraCastro","twitter_site":"@_SiqueiraCastro","twitter_misc":{"Escrito por":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/bolsonaro-enaltece-fim-de-conselhos-com-atuacao-da-sociedade\/#article","isPartOf":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/bolsonaro-enaltece-fim-de-conselhos-com-atuacao-da-sociedade\/"},"author":{"name":"","@id":""},"headline":"Bolsonaro enaltece fim de conselhos com atua\u00e7\u00e3o da sociedade","datePublished":"2019-04-16T13:56:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/bolsonaro-enaltece-fim-de-conselhos-com-atuacao-da-sociedade\/"},"wordCount":79,"commentCount":0,"publisher":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/#organization"},"articleSection":["M\u00eddia"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.siqueiracastro.com.br\/noticias\/bolsonaro-enaltece-fim-de-conselhos-com-atuacao-da-sociedade\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/bolsonaro-enaltece-fim-de-conselhos-com-atuacao-da-sociedade\/","url":"https:\/\/www.siqueiracastro.com.br\/noticias\/bolsonaro-enaltece-fim-de-conselhos-com-atuacao-da-sociedade\/","name":"Bolsonaro enaltece fim de conselhos com atua\u00e7\u00e3o da sociedade - Not\u00edcias | Siqueira Castro","isPartOf":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/#website"},"datePublished":"2019-04-16T13:56:53+00:00","breadcrumb":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/bolsonaro-enaltece-fim-de-conselhos-com-atuacao-da-sociedade\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.siqueiracastro.com.br\/noticias\/bolsonaro-enaltece-fim-de-conselhos-com-atuacao-da-sociedade\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/bolsonaro-enaltece-fim-de-conselhos-com-atuacao-da-sociedade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.siqueiracastro.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Bolsonaro enaltece fim de conselhos com atua\u00e7\u00e3o da sociedade"}]},{"@type":"WebSite","@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/#website","url":"https:\/\/www.siqueiracastro.com.br\/noticias\/","name":"Not\u00edcias | Siqueira Castro","description":"Not\u00edcias Siqueira Castro","publisher":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.siqueiracastro.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/#organization","name":"Not\u00edcias | Siqueira Castro","url":"https:\/\/www.siqueiracastro.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/uploads\/04\/logo-sca-mobile.png","contentUrl":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/uploads\/04\/logo-sca-mobile.png","width":286,"height":70,"caption":"Not\u00edcias | Siqueira Castro"},"image":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/siqueiracastro.advogados","https:\/\/x.com\/_SiqueiraCastro"]},{"@type":"Person","@id":"","url":"https:\/\/www.siqueiracastro.com.br\/noticias\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/posts\/33352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=33352"}],"version-history":[{"count":0,"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/posts\/33352\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=33352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=33352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=33352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}