{"id":33700,"date":"2019-07-23T12:23:01","date_gmt":"2019-07-23T15:23:01","guid":{"rendered":"https:\/\/www.siqueiracastro.com.br\/noticias\/?p=33700"},"modified":"2019-07-23T12:23:05","modified_gmt":"2019-07-23T15:23:05","slug":"multa-e-clausula-petrea-e-nao-pode-ser-extinta","status":"publish","type":"post","link":"https:\/\/www.siqueiracastro.com.br\/noticias\/multa-e-clausula-petrea-e-nao-pode-ser-extinta\/","title":{"rendered":"Multa \u00e9 cl\u00e1usula p\u00e9trea e n\u00e3o pode ser extinta"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Mat\u00e9ria na Folha de S.Paulo atenta para a necessidade de o governo aprovar uma lei caso decida mudar o percentual da multa paga pelo empregador sobre o valor depositado no FGTS ao trabalhador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com o s\u00f3cio Otavio Pinto e Silva, a multa para dispensas sem motivo foi introduzida na Constitui\u00e7\u00e3o de 1988 como forma de prote\u00e7\u00e3o em casos de demiss\u00e3o sem justa causa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Leia <a href=\"https:\/\/www.siqueiracastro.com.br\/noticias\/Noticias\/SCAMidia\/jul-2019\/folha-sp-governo-quer-estimular-novo-fgts.pdf\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"mais (abre numa nova aba)\">mais<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mat\u00e9ria na Folha de S.Paulo atenta para a necessidade de o governo aprovar uma lei caso decida mudar o percentual da multa paga pelo empregador sobre o valor depositado no FGTS ao trabalhador. De acordo com o s\u00f3cio Otavio Pinto e Silva, a multa para dispensas sem motivo foi introduzida na Constitui\u00e7\u00e3o de 1988 como [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[112,128,65,26,110],"class_list":["post-33700","post","type-post","status-publish","format-standard","hentry","category-midia","tag-direito-do-trabalho","tag-fgts","tag-folha-s-paulo","tag-full-solution","tag-otavio-pinto-e-silva"],"fields":{"_edit_lock":["1563895389:4"],"tdc_dirty_content":["1"],"tdc_icon_fonts":["a:0:{}"],"tdc_google_fonts":["a:0:{}"],"_edit_last":["4"],"td_post_theme_settings":["a:2:{s:16:\"td_post_template\";s:15:\"single_template\";s:14:\"td_primary_cat\";s:1:\"6\";}"],"arquivo":[""],"_arquivo":["field_5cd093c67f0aa"],"subtitulo":["Folha de S.Paulo"],"_subtitulo":["field_5cc755a87dc0e"],"fonte":["Otavio Pinto e Silva"],"_fonte":["field_5cc73bceda287"],"post_views_count":["1330"],"entity_url":["\/post\/multa_e_clausula_petrea_e_nao_pode_ser_extinta"]},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Multa \u00e9 cl\u00e1usula p\u00e9trea e n\u00e3o pode ser extinta - Not\u00edcias | Siqueira Castro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.siqueiracastro.com.br\/noticias\/multa-e-clausula-petrea-e-nao-pode-ser-extinta\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Multa \u00e9 cl\u00e1usula p\u00e9trea e n\u00e3o pode ser extinta - Not\u00edcias | Siqueira Castro\" \/>\n<meta property=\"og:description\" content=\"Mat\u00e9ria na Folha de S.Paulo atenta para a necessidade de o governo aprovar uma lei caso decida mudar o percentual da multa paga pelo empregador sobre o valor depositado no FGTS ao trabalhador. De acordo com o s\u00f3cio Otavio Pinto e Silva, a multa para dispensas sem motivo foi introduzida na Constitui\u00e7\u00e3o de 1988 como [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.siqueiracastro.com.br\/noticias\/multa-e-clausula-petrea-e-nao-pode-ser-extinta\/\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias | Siqueira Castro\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/siqueiracastro.advogados\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-23T15:23:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-23T15:23:05+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@_SiqueiraCastro\" \/>\n<meta name=\"twitter:site\" content=\"@_SiqueiraCastro\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/multa-e-clausula-petrea-e-nao-pode-ser-extinta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/multa-e-clausula-petrea-e-nao-pode-ser-extinta\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Multa \u00e9 cl\u00e1usula p\u00e9trea e n\u00e3o pode ser extinta\",\"datePublished\":\"2019-07-23T15:23:01+00:00\",\"dateModified\":\"2019-07-23T15:23:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/multa-e-clausula-petrea-e-nao-pode-ser-extinta\\\/\"},\"wordCount\":83,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/#organization\"},\"keywords\":[\"Direito do Trabalho\",\"FGTS\",\"Folha S Paulo\",\"Full Solution\",\"Otavio Pinto e Silva\"],\"articleSection\":[\"M\u00eddia\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/multa-e-clausula-petrea-e-nao-pode-ser-extinta\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/multa-e-clausula-petrea-e-nao-pode-ser-extinta\\\/\",\"url\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/multa-e-clausula-petrea-e-nao-pode-ser-extinta\\\/\",\"name\":\"Multa \u00e9 cl\u00e1usula p\u00e9trea e n\u00e3o pode ser extinta - Not\u00edcias | Siqueira Castro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/#website\"},\"datePublished\":\"2019-07-23T15:23:01+00:00\",\"dateModified\":\"2019-07-23T15:23:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/multa-e-clausula-petrea-e-nao-pode-ser-extinta\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/multa-e-clausula-petrea-e-nao-pode-ser-extinta\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/multa-e-clausula-petrea-e-nao-pode-ser-extinta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Multa \u00e9 cl\u00e1usula p\u00e9trea e n\u00e3o pode ser extinta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/\",\"name\":\"Not\u00edcias | Siqueira Castro\",\"description\":\"Not\u00edcias Siqueira Castro\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/#organization\",\"name\":\"Not\u00edcias | Siqueira Castro\",\"url\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/wp-content\\\/uploads\\\/04\\\/logo-sca-mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/wp-content\\\/uploads\\\/04\\\/logo-sca-mobile.png\",\"width\":286,\"height\":70,\"caption\":\"Not\u00edcias | Siqueira Castro\"},\"image\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/siqueiracastro.advogados\",\"https:\\\/\\\/x.com\\\/_SiqueiraCastro\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Multa \u00e9 cl\u00e1usula p\u00e9trea e n\u00e3o pode ser extinta - Not\u00edcias | Siqueira Castro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.siqueiracastro.com.br\/noticias\/multa-e-clausula-petrea-e-nao-pode-ser-extinta\/","og_locale":"pt_BR","og_type":"article","og_title":"Multa \u00e9 cl\u00e1usula p\u00e9trea e n\u00e3o pode ser extinta - Not\u00edcias | Siqueira Castro","og_description":"Mat\u00e9ria na Folha de S.Paulo atenta para a necessidade de o governo aprovar uma lei caso decida mudar o percentual da multa paga pelo empregador sobre o valor depositado no FGTS ao trabalhador. De acordo com o s\u00f3cio Otavio Pinto e Silva, a multa para dispensas sem motivo foi introduzida na Constitui\u00e7\u00e3o de 1988 como [&hellip;]","og_url":"https:\/\/www.siqueiracastro.com.br\/noticias\/multa-e-clausula-petrea-e-nao-pode-ser-extinta\/","og_site_name":"Not\u00edcias | Siqueira Castro","article_publisher":"https:\/\/www.facebook.com\/siqueiracastro.advogados","article_published_time":"2019-07-23T15:23:01+00:00","article_modified_time":"2019-07-23T15:23:05+00:00","twitter_card":"summary_large_image","twitter_creator":"@_SiqueiraCastro","twitter_site":"@_SiqueiraCastro","twitter_misc":{"Escrito por":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/multa-e-clausula-petrea-e-nao-pode-ser-extinta\/#article","isPartOf":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/multa-e-clausula-petrea-e-nao-pode-ser-extinta\/"},"author":{"name":"","@id":""},"headline":"Multa \u00e9 cl\u00e1usula p\u00e9trea e n\u00e3o pode ser extinta","datePublished":"2019-07-23T15:23:01+00:00","dateModified":"2019-07-23T15:23:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/multa-e-clausula-petrea-e-nao-pode-ser-extinta\/"},"wordCount":83,"commentCount":0,"publisher":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/#organization"},"keywords":["Direito do Trabalho","FGTS","Folha S Paulo","Full Solution","Otavio Pinto e Silva"],"articleSection":["M\u00eddia"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.siqueiracastro.com.br\/noticias\/multa-e-clausula-petrea-e-nao-pode-ser-extinta\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/multa-e-clausula-petrea-e-nao-pode-ser-extinta\/","url":"https:\/\/www.siqueiracastro.com.br\/noticias\/multa-e-clausula-petrea-e-nao-pode-ser-extinta\/","name":"Multa \u00e9 cl\u00e1usula p\u00e9trea e n\u00e3o pode ser extinta - Not\u00edcias | Siqueira Castro","isPartOf":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/#website"},"datePublished":"2019-07-23T15:23:01+00:00","dateModified":"2019-07-23T15:23:05+00:00","breadcrumb":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/multa-e-clausula-petrea-e-nao-pode-ser-extinta\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.siqueiracastro.com.br\/noticias\/multa-e-clausula-petrea-e-nao-pode-ser-extinta\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/multa-e-clausula-petrea-e-nao-pode-ser-extinta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.siqueiracastro.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Multa \u00e9 cl\u00e1usula p\u00e9trea e n\u00e3o pode ser extinta"}]},{"@type":"WebSite","@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/#website","url":"https:\/\/www.siqueiracastro.com.br\/noticias\/","name":"Not\u00edcias | Siqueira Castro","description":"Not\u00edcias Siqueira Castro","publisher":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.siqueiracastro.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/#organization","name":"Not\u00edcias | Siqueira Castro","url":"https:\/\/www.siqueiracastro.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/uploads\/04\/logo-sca-mobile.png","contentUrl":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/uploads\/04\/logo-sca-mobile.png","width":286,"height":70,"caption":"Not\u00edcias | Siqueira Castro"},"image":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/siqueiracastro.advogados","https:\/\/x.com\/_SiqueiraCastro"]},{"@type":"Person","@id":"","url":"https:\/\/www.siqueiracastro.com.br\/noticias\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/posts\/33700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=33700"}],"version-history":[{"count":2,"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/posts\/33700\/revisions"}],"predecessor-version":[{"id":33702,"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/posts\/33700\/revisions\/33702"}],"wp:attachment":[{"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=33700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=33700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=33700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}