{"id":38263,"date":"2024-04-18T10:10:48","date_gmt":"2024-04-18T13:10:48","guid":{"rendered":"https:\/\/www.siqueiracastro.com.br\/noticias\/?p=38263"},"modified":"2024-04-18T12:27:31","modified_gmt":"2024-04-18T15:27:31","slug":"novo-entendimento-do-stj-altera-o-contrato-de-compra-e-venda-do-imovel-com-alienacao-fiduciaria-em-garantia","status":"publish","type":"post","link":"https:\/\/www.siqueiracastro.com.br\/noticias\/novo-entendimento-do-stj-altera-o-contrato-de-compra-e-venda-do-imovel-com-alienacao-fiduciaria-em-garantia\/","title":{"rendered":"Novo entendimento do STJ altera o contrato de compra e venda do im\u00f3vel com aliena\u00e7\u00e3o fiduci\u00e1ria em garantia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O contrato de aliena\u00e7\u00e3o fiduci\u00e1ria em garantia \u00e9 uma das modalidades contratuais existentes no ordenamento jur\u00eddico que se destina a garantir o cumprimento das obriga\u00e7\u00f5es assumidas pelo devedor fiduciante em rela\u00e7\u00e3o ao credor fiduci\u00e1rio.&nbsp;&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/uploads\/04\/STJ-3n-1024x683.jpeg\" alt=\"\" class=\"wp-image-38255\" srcset=\"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/uploads\/04\/STJ-3n-1024x683.jpeg 1024w, https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/uploads\/04\/STJ-3n-300x200.jpeg 300w, https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/uploads\/04\/STJ-3n-768x512.jpeg 768w, https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/uploads\/04\/STJ-3n-1536x1024.jpeg 1536w, https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/uploads\/04\/STJ-3n-2048x1365.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Neste tipo de contrato, o devedor det\u00e9m a posse direta do im\u00f3vel e o credor recebe a posse indireta, juntamente com o direito de propriedade.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 uma forma de transferir a propriedade ao credor, como forma de garantir o cumprimento das obriga\u00e7\u00f5es assumidas pelo devedor.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Lei n\u00ba 9.514\/1997 estabelece as normas espec\u00edficas para a aliena\u00e7\u00e3o fiduci\u00e1ria em garantia de im\u00f3vel.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O contrato deve conter, obrigatoriamente, as seguintes informa\u00e7\u00f5es: o valor da d\u00edvida garantida, a descri\u00e7\u00e3o do bem alienado, o prazo para o cumprimento da obriga\u00e7\u00e3o, as condi\u00e7\u00f5es para a resolu\u00e7\u00e3o do contrato e as penalidades aplic\u00e1veis em caso de inadimpl\u00eancia.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O registro do contrato na matr\u00edcula do im\u00f3vel confere ao credor a garantia real sobre o bem alienado.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entretanto, nos autos do EREsp n\u00ba 1.866.844, no julgamento dos embargos de diverg\u00eancia, a 2\u00aa Se\u00e7\u00e3o do Superior Tribunal de Justi\u00e7a (STJ) decidiu que, mesmo o contrato n\u00e3o tendo sido registrado no Cart\u00f3rio de Registro de Im\u00f3veis, conforme exigido pelo artigo 23 da Lei n\u00ba 9.514\/97, este fato n\u00e3o invalida ou torna ineficaz os termos acordados livremente entre as partes no contrato de propriedade fiduci\u00e1ria de im\u00f3vel.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nesse passo, o entendimento viabiliza o cumprimento da obriga\u00e7\u00e3o em favor do credor, em caso de inadimpl\u00eancia do devedor, mesmo que a formalidade exigida pela lei, qual seja, registro do contrato de aliena\u00e7\u00e3o fiduci\u00e1ria, n\u00e3o tenha sido cumprida.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O voto do Ministro Ricardo Villas Boas Cueva entende que <em>o registro, conquanto despiciendo para conferir efic\u00e1cia ao contrato de aliena\u00e7\u00e3o fiduci\u00e1ria entre devedor fiduciante e credor fiduci\u00e1rio, \u00e9, sim, imprescind\u00edvel para dar in\u00edcio \u00e0 aliena\u00e7\u00e3o extrajudicial do im\u00f3vel, tendo em vista que a constitui\u00e7\u00e3o do devedor em mora e a eventual purga\u00e7\u00e3o desta se processa perante o oficial de registro de im\u00f3veis, nos moldes do artigo 26 da Lei n\u00ba 9.514\/97.&nbsp;<\/em>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dessa forma, independentemente da responsabilidade da parte para levar a registro o contrato de aliena\u00e7\u00e3o fiduci\u00e1ria, o credor pode, a qualquer tempo, antes de iniciar a aliena\u00e7\u00e3o extrajudicial, proceder o registro na matr\u00edcula do im\u00f3vel.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Resta assim consolidado o entendimento da 2\u00aa se\u00e7\u00e3o do STJ que flexibiliza os requisitos formais para execu\u00e7\u00e3o dos termos do contrato de compra e venda com aliena\u00e7\u00e3o fiduci\u00e1ria em garantia, mesmo que n\u00e3o observadas as formalidades do registro na matr\u00edcula do im\u00f3vel.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta medida refor\u00e7a as teses das institui\u00e7\u00f5es financeiras e de cr\u00e9dito, auxiliando na desburocratiza\u00e7\u00e3o dos procedimentos e visando a efetiva tutela do direito em detrimento da formalidade excessiva.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por fim, importante mencionar que a aus\u00eancia do registro do contrato de aliena\u00e7\u00e3o fiduci\u00e1ria no Registro de Im\u00f3veis n\u00e3o retira a sua efic\u00e1cia, ao menos entre os contratantes, sendo certo que tal provid\u00eancias serve para produzir efeitos perante terceiros, assim como \u00e9 imprescind\u00edvel para a aliena\u00e7\u00e3o extrajudicial do im\u00f3vel, uma vez que a constitui\u00e7\u00e3o em mora do devedor e eventual purga\u00e7\u00e3o desta se processa perante o Cart\u00f3rio de Registro de Im\u00f3veis.\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">EREsp n\u00ba 1.866.844&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O contrato de aliena\u00e7\u00e3o fiduci\u00e1ria em garantia \u00e9 uma das modalidades contratuais existentes no ordenamento jur\u00eddico que se destina a garantir o cumprimento das obriga\u00e7\u00f5es assumidas pelo devedor fiduciante em rela\u00e7\u00e3o ao credor fiduci\u00e1rio.&nbsp;&nbsp; Neste tipo de contrato, o devedor det\u00e9m a posse direta do im\u00f3vel e o credor recebe a posse indireta, juntamente com [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[251],"class_list":["post-38263","post","type-post","status-publish","format-standard","hentry","category-informativos","tag-setor-imobiliario"],"fields":{"_edit_lock":["1713454051:13"],"tdc_dirty_content":["1"],"tdc_icon_fonts":["a:0:{}"],"tdc_google_fonts":["a:0:{}"],"_edit_last":["13"],"arquivo":[""],"_arquivo":["field_5cd093c67f0aa"],"subtitulo":[""],"_subtitulo":["field_5cc755a87dc0e"],"fonte":[""],"_fonte":["field_5cc73bceda287"],"td_post_theme_settings":["a:1:{s:16:\"td_post_template\";s:15:\"single_template\";}"],"_yoast_wpseo_primary_category":["5"],"_yoast_wpseo_focuskw":["Novo entendimento do STJ altera o contrato de compra e venda do im\u00f3vel com aliena\u00e7\u00e3o fiduci\u00e1ria em garantia"],"_yoast_wpseo_metadesc":["O contrato de aliena\u00e7\u00e3o fiduci\u00e1ria em garantia \u00e9 uma das modalidades contratuais existentes no ordenamento jur\u00eddico que se destina a garantir o cumprimento das obriga\u00e7\u00f5es assumidas pelo devedor fiduciante em rela\u00e7\u00e3o ao credor fiduci\u00e1rio."],"_yoast_wpseo_linkdex":["52"],"_yoast_wpseo_content_score":["30"],"_yoast_wpseo_estimated-reading-time-minutes":["4"],"post_views_count":["1356"]},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Novo entendimento do STJ altera o contrato de compra e venda do im\u00f3vel com aliena\u00e7\u00e3o fiduci\u00e1ria em garantia - Not\u00edcias | Siqueira Castro<\/title>\n<meta name=\"description\" content=\"O contrato de aliena\u00e7\u00e3o fiduci\u00e1ria em garantia \u00e9 uma das modalidades contratuais existentes no ordenamento jur\u00eddico que se destina a garantir o cumprimento das obriga\u00e7\u00f5es assumidas pelo devedor fiduciante em rela\u00e7\u00e3o ao credor fiduci\u00e1rio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.siqueiracastro.com.br\/noticias\/novo-entendimento-do-stj-altera-o-contrato-de-compra-e-venda-do-imovel-com-alienacao-fiduciaria-em-garantia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novo entendimento do STJ altera o contrato de compra e venda do im\u00f3vel com aliena\u00e7\u00e3o fiduci\u00e1ria em garantia - Not\u00edcias | Siqueira Castro\" \/>\n<meta property=\"og:description\" content=\"O contrato de aliena\u00e7\u00e3o fiduci\u00e1ria em garantia \u00e9 uma das modalidades contratuais existentes no ordenamento jur\u00eddico que se destina a garantir o cumprimento das obriga\u00e7\u00f5es assumidas pelo devedor fiduciante em rela\u00e7\u00e3o ao credor fiduci\u00e1rio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.siqueiracastro.com.br\/noticias\/novo-entendimento-do-stj-altera-o-contrato-de-compra-e-venda-do-imovel-com-alienacao-fiduciaria-em-garantia\/\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias | Siqueira Castro\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/siqueiracastro.advogados\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-18T13:10:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-18T15:27:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/uploads\/04\/STJ-3n-1024x683.jpeg\" \/>\n<meta name=\"author\" content=\"Annie Pereira Andrade\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@_SiqueiraCastro\" \/>\n<meta name=\"twitter:site\" content=\"@_SiqueiraCastro\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Annie Pereira Andrade\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/novo-entendimento-do-stj-altera-o-contrato-de-compra-e-venda-do-imovel-com-alienacao-fiduciaria-em-garantia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/novo-entendimento-do-stj-altera-o-contrato-de-compra-e-venda-do-imovel-com-alienacao-fiduciaria-em-garantia\\\/\"},\"author\":{\"name\":\"Annie Pereira Andrade\",\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/#\\\/schema\\\/person\\\/b3ad81cd2d679684cb660d7048070c31\"},\"headline\":\"Novo entendimento do STJ altera o contrato de compra e venda do im\u00f3vel com aliena\u00e7\u00e3o fiduci\u00e1ria em garantia\",\"datePublished\":\"2024-04-18T13:10:48+00:00\",\"dateModified\":\"2024-04-18T15:27:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/novo-entendimento-do-stj-altera-o-contrato-de-compra-e-venda-do-imovel-com-alienacao-fiduciaria-em-garantia\\\/\"},\"wordCount\":619,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/novo-entendimento-do-stj-altera-o-contrato-de-compra-e-venda-do-imovel-com-alienacao-fiduciaria-em-garantia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/wp-content\\\/uploads\\\/04\\\/STJ-3n-1024x683.jpeg\",\"keywords\":[\"Setor Imobili\u00e1rio\"],\"articleSection\":[\"Informativos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/novo-entendimento-do-stj-altera-o-contrato-de-compra-e-venda-do-imovel-com-alienacao-fiduciaria-em-garantia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/novo-entendimento-do-stj-altera-o-contrato-de-compra-e-venda-do-imovel-com-alienacao-fiduciaria-em-garantia\\\/\",\"url\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/novo-entendimento-do-stj-altera-o-contrato-de-compra-e-venda-do-imovel-com-alienacao-fiduciaria-em-garantia\\\/\",\"name\":\"Novo entendimento do STJ altera o contrato de compra e venda do im\u00f3vel com aliena\u00e7\u00e3o fiduci\u00e1ria em garantia - Not\u00edcias | Siqueira Castro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/novo-entendimento-do-stj-altera-o-contrato-de-compra-e-venda-do-imovel-com-alienacao-fiduciaria-em-garantia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/novo-entendimento-do-stj-altera-o-contrato-de-compra-e-venda-do-imovel-com-alienacao-fiduciaria-em-garantia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/wp-content\\\/uploads\\\/04\\\/STJ-3n-1024x683.jpeg\",\"datePublished\":\"2024-04-18T13:10:48+00:00\",\"dateModified\":\"2024-04-18T15:27:31+00:00\",\"description\":\"O contrato de aliena\u00e7\u00e3o fiduci\u00e1ria em garantia \u00e9 uma das modalidades contratuais existentes no ordenamento jur\u00eddico que se destina a garantir o cumprimento das obriga\u00e7\u00f5es assumidas pelo devedor fiduciante em rela\u00e7\u00e3o ao credor fiduci\u00e1rio.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/novo-entendimento-do-stj-altera-o-contrato-de-compra-e-venda-do-imovel-com-alienacao-fiduciaria-em-garantia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/novo-entendimento-do-stj-altera-o-contrato-de-compra-e-venda-do-imovel-com-alienacao-fiduciaria-em-garantia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/novo-entendimento-do-stj-altera-o-contrato-de-compra-e-venda-do-imovel-com-alienacao-fiduciaria-em-garantia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/wp-content\\\/uploads\\\/04\\\/STJ-3n-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/wp-content\\\/uploads\\\/04\\\/STJ-3n-scaled.jpeg\",\"width\":2560,\"height\":1707,\"caption\":\"woman showing with one hand a mini house. Real state concept.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/novo-entendimento-do-stj-altera-o-contrato-de-compra-e-venda-do-imovel-com-alienacao-fiduciaria-em-garantia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Novo entendimento do STJ altera o contrato de compra e venda do im\u00f3vel com aliena\u00e7\u00e3o fiduci\u00e1ria em garantia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/\",\"name\":\"Not\u00edcias | Siqueira Castro\",\"description\":\"Not\u00edcias Siqueira Castro\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/#organization\",\"name\":\"Not\u00edcias | Siqueira Castro\",\"url\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/wp-content\\\/uploads\\\/04\\\/logo-sca-mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/wp-content\\\/uploads\\\/04\\\/logo-sca-mobile.png\",\"width\":286,\"height\":70,\"caption\":\"Not\u00edcias | Siqueira Castro\"},\"image\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/siqueiracastro.advogados\",\"https:\\\/\\\/x.com\\\/_SiqueiraCastro\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/#\\\/schema\\\/person\\\/b3ad81cd2d679684cb660d7048070c31\",\"name\":\"Annie Pereira Andrade\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/wp-content\\\/litespeed\\\/avatar\\\/ea8ff2f7d87cd5ad3a1cb5e87cd025b6.jpg?ver=1783610470\",\"url\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/wp-content\\\/litespeed\\\/avatar\\\/ea8ff2f7d87cd5ad3a1cb5e87cd025b6.jpg?ver=1783610470\",\"contentUrl\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/wp-content\\\/litespeed\\\/avatar\\\/ea8ff2f7d87cd5ad3a1cb5e87cd025b6.jpg?ver=1783610470\",\"caption\":\"Annie Pereira Andrade\"},\"url\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/author\\\/annie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Novo entendimento do STJ altera o contrato de compra e venda do im\u00f3vel com aliena\u00e7\u00e3o fiduci\u00e1ria em garantia - Not\u00edcias | Siqueira Castro","description":"O contrato de aliena\u00e7\u00e3o fiduci\u00e1ria em garantia \u00e9 uma das modalidades contratuais existentes no ordenamento jur\u00eddico que se destina a garantir o cumprimento das obriga\u00e7\u00f5es assumidas pelo devedor fiduciante em rela\u00e7\u00e3o ao credor fiduci\u00e1rio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.siqueiracastro.com.br\/noticias\/novo-entendimento-do-stj-altera-o-contrato-de-compra-e-venda-do-imovel-com-alienacao-fiduciaria-em-garantia\/","og_locale":"pt_BR","og_type":"article","og_title":"Novo entendimento do STJ altera o contrato de compra e venda do im\u00f3vel com aliena\u00e7\u00e3o fiduci\u00e1ria em garantia - Not\u00edcias | Siqueira Castro","og_description":"O contrato de aliena\u00e7\u00e3o fiduci\u00e1ria em garantia \u00e9 uma das modalidades contratuais existentes no ordenamento jur\u00eddico que se destina a garantir o cumprimento das obriga\u00e7\u00f5es assumidas pelo devedor fiduciante em rela\u00e7\u00e3o ao credor fiduci\u00e1rio.","og_url":"https:\/\/www.siqueiracastro.com.br\/noticias\/novo-entendimento-do-stj-altera-o-contrato-de-compra-e-venda-do-imovel-com-alienacao-fiduciaria-em-garantia\/","og_site_name":"Not\u00edcias | Siqueira Castro","article_publisher":"https:\/\/www.facebook.com\/siqueiracastro.advogados","article_published_time":"2024-04-18T13:10:48+00:00","article_modified_time":"2024-04-18T15:27:31+00:00","og_image":[{"url":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/uploads\/04\/STJ-3n-1024x683.jpeg","type":"","width":"","height":""}],"author":"Annie Pereira Andrade","twitter_card":"summary_large_image","twitter_creator":"@_SiqueiraCastro","twitter_site":"@_SiqueiraCastro","twitter_misc":{"Escrito por":"Annie Pereira Andrade","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/novo-entendimento-do-stj-altera-o-contrato-de-compra-e-venda-do-imovel-com-alienacao-fiduciaria-em-garantia\/#article","isPartOf":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/novo-entendimento-do-stj-altera-o-contrato-de-compra-e-venda-do-imovel-com-alienacao-fiduciaria-em-garantia\/"},"author":{"name":"Annie Pereira Andrade","@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/#\/schema\/person\/b3ad81cd2d679684cb660d7048070c31"},"headline":"Novo entendimento do STJ altera o contrato de compra e venda do im\u00f3vel com aliena\u00e7\u00e3o fiduci\u00e1ria em garantia","datePublished":"2024-04-18T13:10:48+00:00","dateModified":"2024-04-18T15:27:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/novo-entendimento-do-stj-altera-o-contrato-de-compra-e-venda-do-imovel-com-alienacao-fiduciaria-em-garantia\/"},"wordCount":619,"commentCount":0,"publisher":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/novo-entendimento-do-stj-altera-o-contrato-de-compra-e-venda-do-imovel-com-alienacao-fiduciaria-em-garantia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/uploads\/04\/STJ-3n-1024x683.jpeg","keywords":["Setor Imobili\u00e1rio"],"articleSection":["Informativos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.siqueiracastro.com.br\/noticias\/novo-entendimento-do-stj-altera-o-contrato-de-compra-e-venda-do-imovel-com-alienacao-fiduciaria-em-garantia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/novo-entendimento-do-stj-altera-o-contrato-de-compra-e-venda-do-imovel-com-alienacao-fiduciaria-em-garantia\/","url":"https:\/\/www.siqueiracastro.com.br\/noticias\/novo-entendimento-do-stj-altera-o-contrato-de-compra-e-venda-do-imovel-com-alienacao-fiduciaria-em-garantia\/","name":"Novo entendimento do STJ altera o contrato de compra e venda do im\u00f3vel com aliena\u00e7\u00e3o fiduci\u00e1ria em garantia - Not\u00edcias | Siqueira Castro","isPartOf":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/novo-entendimento-do-stj-altera-o-contrato-de-compra-e-venda-do-imovel-com-alienacao-fiduciaria-em-garantia\/#primaryimage"},"image":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/novo-entendimento-do-stj-altera-o-contrato-de-compra-e-venda-do-imovel-com-alienacao-fiduciaria-em-garantia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/uploads\/04\/STJ-3n-1024x683.jpeg","datePublished":"2024-04-18T13:10:48+00:00","dateModified":"2024-04-18T15:27:31+00:00","description":"O contrato de aliena\u00e7\u00e3o fiduci\u00e1ria em garantia \u00e9 uma das modalidades contratuais existentes no ordenamento jur\u00eddico que se destina a garantir o cumprimento das obriga\u00e7\u00f5es assumidas pelo devedor fiduciante em rela\u00e7\u00e3o ao credor fiduci\u00e1rio.","breadcrumb":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/novo-entendimento-do-stj-altera-o-contrato-de-compra-e-venda-do-imovel-com-alienacao-fiduciaria-em-garantia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.siqueiracastro.com.br\/noticias\/novo-entendimento-do-stj-altera-o-contrato-de-compra-e-venda-do-imovel-com-alienacao-fiduciaria-em-garantia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/novo-entendimento-do-stj-altera-o-contrato-de-compra-e-venda-do-imovel-com-alienacao-fiduciaria-em-garantia\/#primaryimage","url":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/uploads\/04\/STJ-3n-scaled.jpeg","contentUrl":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/uploads\/04\/STJ-3n-scaled.jpeg","width":2560,"height":1707,"caption":"woman showing with one hand a mini house. Real state concept."},{"@type":"BreadcrumbList","@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/novo-entendimento-do-stj-altera-o-contrato-de-compra-e-venda-do-imovel-com-alienacao-fiduciaria-em-garantia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.siqueiracastro.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Novo entendimento do STJ altera o contrato de compra e venda do im\u00f3vel com aliena\u00e7\u00e3o fiduci\u00e1ria em garantia"}]},{"@type":"WebSite","@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/#website","url":"https:\/\/www.siqueiracastro.com.br\/noticias\/","name":"Not\u00edcias | Siqueira Castro","description":"Not\u00edcias Siqueira Castro","publisher":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.siqueiracastro.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/#organization","name":"Not\u00edcias | Siqueira Castro","url":"https:\/\/www.siqueiracastro.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/uploads\/04\/logo-sca-mobile.png","contentUrl":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/uploads\/04\/logo-sca-mobile.png","width":286,"height":70,"caption":"Not\u00edcias | Siqueira Castro"},"image":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/siqueiracastro.advogados","https:\/\/x.com\/_SiqueiraCastro"]},{"@type":"Person","@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/#\/schema\/person\/b3ad81cd2d679684cb660d7048070c31","name":"Annie Pereira Andrade","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/litespeed\/avatar\/ea8ff2f7d87cd5ad3a1cb5e87cd025b6.jpg?ver=1783610470","url":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/litespeed\/avatar\/ea8ff2f7d87cd5ad3a1cb5e87cd025b6.jpg?ver=1783610470","contentUrl":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/litespeed\/avatar\/ea8ff2f7d87cd5ad3a1cb5e87cd025b6.jpg?ver=1783610470","caption":"Annie Pereira Andrade"},"url":"https:\/\/www.siqueiracastro.com.br\/noticias\/author\/annie\/"}]}},"_links":{"self":[{"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/posts\/38263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=38263"}],"version-history":[{"count":2,"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/posts\/38263\/revisions"}],"predecessor-version":[{"id":38271,"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/posts\/38263\/revisions\/38271"}],"wp:attachment":[{"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=38263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=38263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=38263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}