{"id":38351,"date":"2024-06-17T11:11:52","date_gmt":"2024-06-17T14:11:52","guid":{"rendered":"https:\/\/www.siqueiracastro.com.br\/noticias\/?p=38351"},"modified":"2024-06-17T11:11:53","modified_gmt":"2024-06-17T14:11:53","slug":"governo-envia-segundo-projeto-de-lei-complementar-que-regulamenta-a-reforma-tributaria-sobre-o-consumo","status":"publish","type":"post","link":"https:\/\/www.siqueiracastro.com.br\/noticias\/governo-envia-segundo-projeto-de-lei-complementar-que-regulamenta-a-reforma-tributaria-sobre-o-consumo\/","title":{"rendered":"Governo envia segundo projeto de lei complementar que regulamenta a Reforma Tribut\u00e1ria sobre o Consumo\u00a0"},"content":{"rendered":"\n<p>No \u00faltimo dia 04 de junho de 2024, o Poder Executivo Federal apresentou ao Congresso Nacional o Projeto de Lei Complementar (PLP) n\u00ba 108\/2024, visando dar prosseguimento \u00e0 fase de regulamenta\u00e7\u00e3o da Reforma Tribut\u00e1ria sobre o Consumo, que foi aprovada em dezembro de 2023 pela Emenda Constitucional n\u00ba 132\/2023.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"870\" height=\"450\" src=\"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/uploads\/06\/reforma-tributaria-setima.jpg\" alt=\"\" class=\"wp-image-38336\" srcset=\"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/uploads\/06\/reforma-tributaria-setima.jpg 870w, https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/uploads\/06\/reforma-tributaria-setima-300x155.jpg 300w, https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/uploads\/06\/reforma-tributaria-setima-768x397.jpg 768w\" sizes=\"auto, (max-width: 870px) 100vw, 870px\" \/><\/figure>\n\n\n\n<p>Antes do envio do PLP n\u00ba 108\/2024, o Governo Federal j\u00e1 havia submetido ao Congresso Nacional o primeiro PLP n\u00ba 68\/2024 em 25 de abril para regulamentar, entre outros temas, os regimes diferenciados, o Imposto Seletivo e da Cesta B\u00e1sica Nacional.&nbsp;<\/p>\n\n\n\n<p>Neste segundo PLP n\u00ba 108\/2024, est\u00e3o sendo estabelecidas diretrizes e compet\u00eancias do Comit\u00ea Gestor do IBS (Imposto sobre Bens e Servi\u00e7os), o regramento do contencioso administrativo do IBS, a distribui\u00e7\u00e3o subnacional de receitas do IBS, o ressarcimento dos saldos credores do ICMS acumulados at\u00e9 dezembro de 2032, bem como altera\u00e7\u00f5es sobre o Imposto sobre Transmiss\u00e3o Causa Mortis e Doa\u00e7\u00e3o (ITCMD) e o Imposto sobre Transmiss\u00e3o Inter Vivos, por ato oneroso, de Bens Im\u00f3veis e de direitos a eles associados (ITBI).&nbsp;<\/p>\n\n\n\n<p>A inst\u00e2ncia m\u00e1xima de delibera\u00e7\u00e3o do Comit\u00ea Gestor do IBS ser\u00e1 o Conselho Superior, que ser\u00e1 composto por 54 membros, dos quais 27 representar\u00e3o cada Estado e o Distrito Federal e outros 27 representar\u00e3o o conjunto dos munic\u00edpios e do Distrito Federal, sendo que neste \u00faltimo caso os representantes dos munic\u00edpios ser\u00e3o escolhidos por meio de elei\u00e7\u00f5es entre os munic\u00edpios.&nbsp;<\/p>\n\n\n\n<p>No \u00e2mbito do julgamento dos processos administrativos existir\u00e3o 3 inst\u00e2ncias de julgamento (Primeira Inst\u00e2ncia, Inst\u00e2ncia Recursal e C\u00e2mara Superior). A primeira inst\u00e2ncia ser\u00e1 composta por 27 c\u00e2maras de julgamento, uma para cada estado, que analisar\u00e1 tamb\u00e9m as autua\u00e7\u00f5es lavradas pelos munic\u00edpios pertencentes \u00e0 unidade federativa. Cada c\u00e2mara ser\u00e1 composta por quatro julgadores: dois servidores indicados pelo estado e dois pelos munic\u00edpios. A segunda inst\u00e2ncia tamb\u00e9m ser\u00e1 composta por 27 c\u00e2maras de julgamento, contudo, ser\u00e3o compostas por 4 representantes fiscais e 4 representantes de contribuintes. A \u00faltima inst\u00e2ncia, a C\u00e2mara Superior, ser\u00e1 composta por 8 julgadores representantes fiscais, que ter\u00e3o a atribui\u00e7\u00e3o de uniformizar os entendimentos do \u00f3rg\u00e3o sobre o IBS.&nbsp;<\/p>\n\n\n\n<p>Acerca do ressarcimento dos saldos credores de ICMS acumulados at\u00e9 31 de dezembro de 2032, eles ser\u00e3o atualizados pela varia\u00e7\u00e3o mensal do IPCA do segundo m\u00eas anterior, sendo necess\u00e1rio requerer a sua homologa\u00e7\u00e3o do saldo credor at\u00e9 1\u00ba de janeiro de 2038 (5 anos a partir dia 1\u00b0 de janeiro de 2033), ao Estado ou Distrito Federal, que dever\u00e1 responder em at\u00e9 60 dias, se referente \u00e0 aquisi\u00e7\u00e3o de bens para o ativo permanente, ou em at\u00e9 24 meses, nos demais casos.&nbsp;<\/p>\n\n\n\n<p>Referido saldo credor poder\u00e1: (i) ser compensado com d\u00e9bitos de ICMS remanescentes; (ii) compensado com d\u00e9bitos de IBS, sendo pelo prazo remanescente, se relativos a bens do ativo permanente, ou em 240 parcelas mensais, nos demais casos; (iii) transferido a terceiros, a partir de 2038, s\u00f3 podendo ser usado para compensa\u00e7\u00e3o no \u00e2mbito do mesmo ente federativo; (iv) ressarcido, em caso de impossibilidade das op\u00e7\u00f5es anteriores, o que ocorrer\u00e1 em at\u00e9 90 dias ap\u00f3s o encerramento do m\u00eas em que ocorreria a respectiva compensa\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p>No tocante ao ITCMD, apesar de n\u00e3o ser estar vinculado \u00e0 Reforma Tribut\u00e1ria sobre o Consumo, o projeto prev\u00ea, al\u00e9m da progressividade do imposto em raz\u00e3o do valor do quinh\u00e3o, legado ou doa\u00e7\u00e3o e a possibilidade de serem celebrados acordos para evitar a dupla tributa\u00e7\u00e3o de heran\u00e7as e doa\u00e7\u00f5es, que o seu fato gerador abranger\u00e1 tamb\u00e9m os aportes financeiros capitalizados sob a forma de planos de previd\u00eancia privada ou qualquer outra forma ou denomina\u00e7\u00e3o de aplica\u00e7\u00e3o financeira ou investimento, bem como daqueles atos societ\u00e1rios que resultem em benef\u00edcios desproporcionais para s\u00f3cio ou acionistas e perd\u00e3o por d\u00edvida praticado por liberalidade e sem justificativa negocial.&nbsp;<\/p>\n\n\n\n<p>Em rela\u00e7\u00e3o ao ITBI, o projeto prev\u00ea que o fato gerador do imposto passe a ocorrer no momento da celebra\u00e7\u00e3o do ato ou t\u00edtulo translativo oneroso do bem im\u00f3vel ou do direito real sobre bem im\u00f3vel, assim como no momento da cess\u00e3o onerosa de direitos relativos \u00e0 aquisi\u00e7\u00e3o de bem im\u00f3vel. Em um primeiro olhar, a pretexto de regulamentar a reforma tribut\u00e1ria, o projeto visa alterar o entendimento consolidado do Poder Judici\u00e1rio no sentido de que a ocorr\u00eancia do fato gerador do ITBI se d\u00e1 no momento do registro imobili\u00e1rio, e n\u00e3o da celebra\u00e7\u00e3o do ato.&nbsp;<\/p>\n\n\n\n<p>Continuaremos acompanhando todas as mudan\u00e7as acerca da regulamenta\u00e7\u00e3o da Reforma Tribut\u00e1ria sobre o Consumo, estando nossa equipe tribut\u00e1ria \u00e0 disposi\u00e7\u00e3o para dirimir quaisquer d\u00favidas acerca do tema.&nbsp;<\/p>\n\n\n\n<p>(Projeto de Lei Complementar 108\/2024)&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No \u00faltimo dia 04 de junho de 2024, o Poder Executivo Federal apresentou ao Congresso Nacional o Projeto de Lei Complementar (PLP) n\u00ba 108\/2024, visando dar prosseguimento \u00e0 fase de regulamenta\u00e7\u00e3o da Reforma Tribut\u00e1ria sobre o Consumo, que foi aprovada em dezembro de 2023 pela Emenda Constitucional n\u00ba 132\/2023.&nbsp; Antes do envio do PLP n\u00ba [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[87],"class_list":["post-38351","post","type-post","status-publish","format-standard","hentry","category-informativos","tag-tributario"],"fields":{"_edit_lock":["1718633597:13"],"_edit_last":["13"],"arquivo":[""],"_arquivo":["field_5cd093c67f0aa"],"subtitulo":[""],"_subtitulo":["field_5cc755a87dc0e"],"fonte":[""],"_fonte":["field_5cc73bceda287"],"td_post_theme_settings":["a:1:{s:16:\"td_post_template\";s:15:\"single_template\";}"],"_yoast_wpseo_primary_category":["5"],"_yoast_wpseo_focuskw":["Governo envia segundo projeto de lei complementar que regulamenta a Reforma Tribut\u00e1ria sobre o Consumo\u00a0"],"_yoast_wpseo_metadesc":["No \u00faltimo dia 04 de junho de 2024, o Poder Executivo Federal apresentou ao Congresso Nacional o Projeto de Lei Complementar (PLP) n\u00ba 108\/2024, visando dar prosseguimento \u00e0 fase de regulamenta\u00e7\u00e3o da Reforma Tribut\u00e1ria sobre o Consumo, que foi aprovada em dezembro de 2023 pela Emenda Constitucional n\u00ba 132\/2023.\u00a0"],"_yoast_wpseo_linkdex":["48"],"_yoast_wpseo_content_score":["30"],"_yoast_wpseo_estimated-reading-time-minutes":["5"],"post_views_count":["387"]},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Governo envia segundo projeto de lei complementar que regulamenta a Reforma Tribut\u00e1ria sobre o Consumo\u00a0 - Not\u00edcias | Siqueira Castro<\/title>\n<meta name=\"description\" content=\"No \u00faltimo dia 04 de junho de 2024, o Poder Executivo Federal apresentou ao Congresso Nacional o Projeto de Lei Complementar (PLP) n\u00ba 108\/2024, visando dar prosseguimento \u00e0 fase de regulamenta\u00e7\u00e3o da Reforma Tribut\u00e1ria sobre o Consumo, que foi aprovada em dezembro de 2023 pela Emenda Constitucional n\u00ba 132\/2023.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.siqueiracastro.com.br\/noticias\/governo-envia-segundo-projeto-de-lei-complementar-que-regulamenta-a-reforma-tributaria-sobre-o-consumo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Governo envia segundo projeto de lei complementar que regulamenta a Reforma Tribut\u00e1ria sobre o Consumo\u00a0 - Not\u00edcias | Siqueira Castro\" \/>\n<meta property=\"og:description\" content=\"No \u00faltimo dia 04 de junho de 2024, o Poder Executivo Federal apresentou ao Congresso Nacional o Projeto de Lei Complementar (PLP) n\u00ba 108\/2024, visando dar prosseguimento \u00e0 fase de regulamenta\u00e7\u00e3o da Reforma Tribut\u00e1ria sobre o Consumo, que foi aprovada em dezembro de 2023 pela Emenda Constitucional n\u00ba 132\/2023.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.siqueiracastro.com.br\/noticias\/governo-envia-segundo-projeto-de-lei-complementar-que-regulamenta-a-reforma-tributaria-sobre-o-consumo\/\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias | Siqueira Castro\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/siqueiracastro.advogados\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-17T14:11:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-17T14:11:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/uploads\/06\/reforma-tributaria-setima.jpg\" \/>\n<meta name=\"author\" content=\"Annie Pereira Andrade\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@_SiqueiraCastro\" \/>\n<meta name=\"twitter:site\" content=\"@_SiqueiraCastro\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Annie Pereira Andrade\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/governo-envia-segundo-projeto-de-lei-complementar-que-regulamenta-a-reforma-tributaria-sobre-o-consumo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/governo-envia-segundo-projeto-de-lei-complementar-que-regulamenta-a-reforma-tributaria-sobre-o-consumo\\\/\"},\"author\":{\"name\":\"Annie Pereira Andrade\",\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/#\\\/schema\\\/person\\\/b3ad81cd2d679684cb660d7048070c31\"},\"headline\":\"Governo envia segundo projeto de lei complementar que regulamenta a Reforma Tribut\u00e1ria sobre o Consumo\u00a0\",\"datePublished\":\"2024-06-17T14:11:52+00:00\",\"dateModified\":\"2024-06-17T14:11:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/governo-envia-segundo-projeto-de-lei-complementar-que-regulamenta-a-reforma-tributaria-sobre-o-consumo\\\/\"},\"wordCount\":821,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/governo-envia-segundo-projeto-de-lei-complementar-que-regulamenta-a-reforma-tributaria-sobre-o-consumo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/wp-content\\\/uploads\\\/06\\\/reforma-tributaria-setima.jpg\",\"keywords\":[\"Tribut\u00e1rio\"],\"articleSection\":[\"Informativos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/governo-envia-segundo-projeto-de-lei-complementar-que-regulamenta-a-reforma-tributaria-sobre-o-consumo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/governo-envia-segundo-projeto-de-lei-complementar-que-regulamenta-a-reforma-tributaria-sobre-o-consumo\\\/\",\"url\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/governo-envia-segundo-projeto-de-lei-complementar-que-regulamenta-a-reforma-tributaria-sobre-o-consumo\\\/\",\"name\":\"Governo envia segundo projeto de lei complementar que regulamenta a Reforma Tribut\u00e1ria sobre o Consumo\u00a0 - Not\u00edcias | Siqueira Castro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/governo-envia-segundo-projeto-de-lei-complementar-que-regulamenta-a-reforma-tributaria-sobre-o-consumo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/governo-envia-segundo-projeto-de-lei-complementar-que-regulamenta-a-reforma-tributaria-sobre-o-consumo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/wp-content\\\/uploads\\\/06\\\/reforma-tributaria-setima.jpg\",\"datePublished\":\"2024-06-17T14:11:52+00:00\",\"dateModified\":\"2024-06-17T14:11:53+00:00\",\"description\":\"No \u00faltimo dia 04 de junho de 2024, o Poder Executivo Federal apresentou ao Congresso Nacional o Projeto de Lei Complementar (PLP) n\u00ba 108\\\/2024, visando dar prosseguimento \u00e0 fase de regulamenta\u00e7\u00e3o da Reforma Tribut\u00e1ria sobre o Consumo, que foi aprovada em dezembro de 2023 pela Emenda Constitucional n\u00ba 132\\\/2023.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/governo-envia-segundo-projeto-de-lei-complementar-que-regulamenta-a-reforma-tributaria-sobre-o-consumo\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/governo-envia-segundo-projeto-de-lei-complementar-que-regulamenta-a-reforma-tributaria-sobre-o-consumo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/governo-envia-segundo-projeto-de-lei-complementar-que-regulamenta-a-reforma-tributaria-sobre-o-consumo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/wp-content\\\/uploads\\\/06\\\/reforma-tributaria-setima.jpg\",\"contentUrl\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/wp-content\\\/uploads\\\/06\\\/reforma-tributaria-setima.jpg\",\"width\":870,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/governo-envia-segundo-projeto-de-lei-complementar-que-regulamenta-a-reforma-tributaria-sobre-o-consumo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Governo envia segundo projeto de lei complementar que regulamenta a Reforma Tribut\u00e1ria sobre o Consumo\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/\",\"name\":\"Not\u00edcias | Siqueira Castro\",\"description\":\"Not\u00edcias Siqueira Castro\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/#organization\",\"name\":\"Not\u00edcias | Siqueira Castro\",\"url\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/wp-content\\\/uploads\\\/04\\\/logo-sca-mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/wp-content\\\/uploads\\\/04\\\/logo-sca-mobile.png\",\"width\":286,\"height\":70,\"caption\":\"Not\u00edcias | Siqueira Castro\"},\"image\":{\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/siqueiracastro.advogados\",\"https:\\\/\\\/x.com\\\/_SiqueiraCastro\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/#\\\/schema\\\/person\\\/b3ad81cd2d679684cb660d7048070c31\",\"name\":\"Annie Pereira Andrade\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/wp-content\\\/litespeed\\\/avatar\\\/ea8ff2f7d87cd5ad3a1cb5e87cd025b6.jpg?ver=1778166155\",\"url\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/wp-content\\\/litespeed\\\/avatar\\\/ea8ff2f7d87cd5ad3a1cb5e87cd025b6.jpg?ver=1778166155\",\"contentUrl\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/wp-content\\\/litespeed\\\/avatar\\\/ea8ff2f7d87cd5ad3a1cb5e87cd025b6.jpg?ver=1778166155\",\"caption\":\"Annie Pereira Andrade\"},\"url\":\"https:\\\/\\\/www.siqueiracastro.com.br\\\/noticias\\\/author\\\/annie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Governo envia segundo projeto de lei complementar que regulamenta a Reforma Tribut\u00e1ria sobre o Consumo\u00a0 - Not\u00edcias | Siqueira Castro","description":"No \u00faltimo dia 04 de junho de 2024, o Poder Executivo Federal apresentou ao Congresso Nacional o Projeto de Lei Complementar (PLP) n\u00ba 108\/2024, visando dar prosseguimento \u00e0 fase de regulamenta\u00e7\u00e3o da Reforma Tribut\u00e1ria sobre o Consumo, que foi aprovada em dezembro de 2023 pela Emenda Constitucional n\u00ba 132\/2023.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.siqueiracastro.com.br\/noticias\/governo-envia-segundo-projeto-de-lei-complementar-que-regulamenta-a-reforma-tributaria-sobre-o-consumo\/","og_locale":"pt_BR","og_type":"article","og_title":"Governo envia segundo projeto de lei complementar que regulamenta a Reforma Tribut\u00e1ria sobre o Consumo\u00a0 - Not\u00edcias | Siqueira Castro","og_description":"No \u00faltimo dia 04 de junho de 2024, o Poder Executivo Federal apresentou ao Congresso Nacional o Projeto de Lei Complementar (PLP) n\u00ba 108\/2024, visando dar prosseguimento \u00e0 fase de regulamenta\u00e7\u00e3o da Reforma Tribut\u00e1ria sobre o Consumo, que foi aprovada em dezembro de 2023 pela Emenda Constitucional n\u00ba 132\/2023.\u00a0","og_url":"https:\/\/www.siqueiracastro.com.br\/noticias\/governo-envia-segundo-projeto-de-lei-complementar-que-regulamenta-a-reforma-tributaria-sobre-o-consumo\/","og_site_name":"Not\u00edcias | Siqueira Castro","article_publisher":"https:\/\/www.facebook.com\/siqueiracastro.advogados","article_published_time":"2024-06-17T14:11:52+00:00","article_modified_time":"2024-06-17T14:11:53+00:00","og_image":[{"url":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/uploads\/06\/reforma-tributaria-setima.jpg","type":"","width":"","height":""}],"author":"Annie Pereira Andrade","twitter_card":"summary_large_image","twitter_creator":"@_SiqueiraCastro","twitter_site":"@_SiqueiraCastro","twitter_misc":{"Escrito por":"Annie Pereira Andrade","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/governo-envia-segundo-projeto-de-lei-complementar-que-regulamenta-a-reforma-tributaria-sobre-o-consumo\/#article","isPartOf":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/governo-envia-segundo-projeto-de-lei-complementar-que-regulamenta-a-reforma-tributaria-sobre-o-consumo\/"},"author":{"name":"Annie Pereira Andrade","@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/#\/schema\/person\/b3ad81cd2d679684cb660d7048070c31"},"headline":"Governo envia segundo projeto de lei complementar que regulamenta a Reforma Tribut\u00e1ria sobre o Consumo\u00a0","datePublished":"2024-06-17T14:11:52+00:00","dateModified":"2024-06-17T14:11:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/governo-envia-segundo-projeto-de-lei-complementar-que-regulamenta-a-reforma-tributaria-sobre-o-consumo\/"},"wordCount":821,"commentCount":0,"publisher":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/governo-envia-segundo-projeto-de-lei-complementar-que-regulamenta-a-reforma-tributaria-sobre-o-consumo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/uploads\/06\/reforma-tributaria-setima.jpg","keywords":["Tribut\u00e1rio"],"articleSection":["Informativos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.siqueiracastro.com.br\/noticias\/governo-envia-segundo-projeto-de-lei-complementar-que-regulamenta-a-reforma-tributaria-sobre-o-consumo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/governo-envia-segundo-projeto-de-lei-complementar-que-regulamenta-a-reforma-tributaria-sobre-o-consumo\/","url":"https:\/\/www.siqueiracastro.com.br\/noticias\/governo-envia-segundo-projeto-de-lei-complementar-que-regulamenta-a-reforma-tributaria-sobre-o-consumo\/","name":"Governo envia segundo projeto de lei complementar que regulamenta a Reforma Tribut\u00e1ria sobre o Consumo\u00a0 - Not\u00edcias | Siqueira Castro","isPartOf":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/governo-envia-segundo-projeto-de-lei-complementar-que-regulamenta-a-reforma-tributaria-sobre-o-consumo\/#primaryimage"},"image":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/governo-envia-segundo-projeto-de-lei-complementar-que-regulamenta-a-reforma-tributaria-sobre-o-consumo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/uploads\/06\/reforma-tributaria-setima.jpg","datePublished":"2024-06-17T14:11:52+00:00","dateModified":"2024-06-17T14:11:53+00:00","description":"No \u00faltimo dia 04 de junho de 2024, o Poder Executivo Federal apresentou ao Congresso Nacional o Projeto de Lei Complementar (PLP) n\u00ba 108\/2024, visando dar prosseguimento \u00e0 fase de regulamenta\u00e7\u00e3o da Reforma Tribut\u00e1ria sobre o Consumo, que foi aprovada em dezembro de 2023 pela Emenda Constitucional n\u00ba 132\/2023.\u00a0","breadcrumb":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/governo-envia-segundo-projeto-de-lei-complementar-que-regulamenta-a-reforma-tributaria-sobre-o-consumo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.siqueiracastro.com.br\/noticias\/governo-envia-segundo-projeto-de-lei-complementar-que-regulamenta-a-reforma-tributaria-sobre-o-consumo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/governo-envia-segundo-projeto-de-lei-complementar-que-regulamenta-a-reforma-tributaria-sobre-o-consumo\/#primaryimage","url":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/uploads\/06\/reforma-tributaria-setima.jpg","contentUrl":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/uploads\/06\/reforma-tributaria-setima.jpg","width":870,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/governo-envia-segundo-projeto-de-lei-complementar-que-regulamenta-a-reforma-tributaria-sobre-o-consumo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.siqueiracastro.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Governo envia segundo projeto de lei complementar que regulamenta a Reforma Tribut\u00e1ria sobre o Consumo\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/#website","url":"https:\/\/www.siqueiracastro.com.br\/noticias\/","name":"Not\u00edcias | Siqueira Castro","description":"Not\u00edcias Siqueira Castro","publisher":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.siqueiracastro.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/#organization","name":"Not\u00edcias | Siqueira Castro","url":"https:\/\/www.siqueiracastro.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/uploads\/04\/logo-sca-mobile.png","contentUrl":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/uploads\/04\/logo-sca-mobile.png","width":286,"height":70,"caption":"Not\u00edcias | Siqueira Castro"},"image":{"@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/siqueiracastro.advogados","https:\/\/x.com\/_SiqueiraCastro"]},{"@type":"Person","@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/#\/schema\/person\/b3ad81cd2d679684cb660d7048070c31","name":"Annie Pereira Andrade","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/litespeed\/avatar\/ea8ff2f7d87cd5ad3a1cb5e87cd025b6.jpg?ver=1778166155","url":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/litespeed\/avatar\/ea8ff2f7d87cd5ad3a1cb5e87cd025b6.jpg?ver=1778166155","contentUrl":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-content\/litespeed\/avatar\/ea8ff2f7d87cd5ad3a1cb5e87cd025b6.jpg?ver=1778166155","caption":"Annie Pereira Andrade"},"url":"https:\/\/www.siqueiracastro.com.br\/noticias\/author\/annie\/"}]}},"_links":{"self":[{"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/posts\/38351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=38351"}],"version-history":[{"count":1,"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/posts\/38351\/revisions"}],"predecessor-version":[{"id":38354,"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/posts\/38351\/revisions\/38354"}],"wp:attachment":[{"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=38351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=38351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.siqueiracastro.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=38351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}